{"id":1675,"date":"2021-11-29T22:57:34","date_gmt":"2021-11-29T21:57:34","guid":{"rendered":"https:\/\/sfrms-app.fr\/?post_type=glossary&#038;p=1675"},"modified":"2021-11-29T22:57:34","modified_gmt":"2021-11-29T21:57:34","slug":"epoque-de-sommeil","status":"publish","type":"glossary","link":"https:\/\/sfrms-app.fr\/index.php\/glossary\/epoque-de-sommeil\/","title":{"rendered":"\u00c9poque de sommeil"},"content":{"rendered":"<p>Intervalle de temps servant d&rsquo;unit&eacute; de base lors de l&rsquo;analyse des stades d&rsquo;un enregistrement de <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/sommeil\/\" title=\"Glossary: Sommeil\"  class=\"glossaryLink\">sommeil<\/a>, typiquement de 30 secondes.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Intervalle de temps servant d&rsquo;unit&eacute; de base lors de l&rsquo;analyse des stades d&rsquo;un enregistrement de sommeil, typiquement de 30 secondes.<\/p>\n","protected":false},"author":1,"featured_media":0,"menu_order":0,"template":"","meta":{"footnotes":""},"glossary-cat":[],"class_list":["post-1675","glossary","type-glossary","status-publish","hentry"],"featured_image_src":null,"_links":{"self":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/glossary\/1675","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":1,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/glossary\/1675\/revisions"}],"predecessor-version":[{"id":1676,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/glossary\/1675\/revisions\/1676"}],"wp:attachment":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1675"}],"wp:term":[{"taxonomy":"glossary-cat","embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/glossary-cat?post=1675"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}