{"id":1031,"date":"2021-11-23T00:24:08","date_gmt":"2021-11-22T23:24:08","guid":{"rendered":"https:\/\/sfrms-app.fr\/?p=1031"},"modified":"2022-10-17T08:51:33","modified_gmt":"2022-10-17T06:51:33","slug":"test-de-maintien-deveil","status":"publish","type":"post","link":"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/23\/test-de-maintien-deveil\/","title":{"rendered":"Test de maintien d\u2019\u00e9veil"},"content":{"rendered":"<h2><span style=\"font-size: 14pt;\">D&eacute;finition<\/span><\/h2>\n<ul>\n<li>Le test de maintien d&rsquo;&eacute;veil (TME) est un examen paraclinique sp&eacute;cifique &agrave; l&rsquo;exploration du <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/sommeil\/\" title=\"Glossary: Sommeil\"  class=\"glossaryLink\">sommeil<\/a>.<\/li>\n<li>Le TME est une mesure de la <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/latence-dendormissement\/\" title=\"Glossary: Latence d'endormissement\" class=\"glossaryLink\">latence d&rsquo;endormissement<\/a> (LE) en conditions contr&ocirc;l&eacute;es.<\/li>\n<li>La LE est mesur&eacute;e sur un <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/hypnogramme\/\" title=\"Glossary: Hypnogramme\" class=\"glossaryLink\">hypnogramme<\/a><\/strong> r&eacute;alis&eacute; sur chaque test.<\/li>\n<li>Les conditions contr&ocirc;l&eacute;es sont :\n<ul>\n<li>4 tests d&rsquo;une dur&eacute;e de 40 min, arr&ecirc;t&eacute; soit apr&egrave;s la survenue de 3 &eacute;poques successives de stade 1 ou une &eacute;poque d&rsquo;un autre <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/stade-de-sommeil\/\" title=\"Glossary: Stade de sommeil\" class=\"glossaryLink\">stade de sommeil<\/a>,<\/li>\n<li>Le premier test d&eacute;bute 1,5 &agrave; 3 h apr&egrave;s l&rsquo;heure habituelle de r&eacute;veil du patient (g&eacute;n&eacute;ralement entre 9 h et 10 h),<\/li>\n<li>Sous surveillance vid&eacute;o,<\/li>\n<li>Espac&eacute;s de 2 heures,<\/li>\n<li>Assis confortablement au lit, dans une pi&egrave;ce faiblement &eacute;clair&eacute;e (0,1 lux), la t&ecirc;te maintenue confortablement par un oreiller (pour &eacute;viter la chute de la t&ecirc;te en cas d&rsquo;<a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/endormissement\/\" title=\"Glossary: Endormissement\" class=\"glossaryLink\">endormissement<\/a>),<\/li>\n<li>&nbsp;Consigne : &laquo; Restez &eacute;veill&eacute;, luttez contre le sommeil, gardez les yeux ouverts, regardez devant vous sans regarder la lumi&egrave;re &raquo;.<\/li>\n<\/ul>\n<\/li>\n<li>Le TME est une mesure objective de la capacit&eacute; &agrave; se maintenir &eacute;veill&eacute; en conditions propices &agrave; l&rsquo;endormissement.<\/li>\n<li>Une &eacute;valuation subjective de la <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/somnolence\/\" title=\"Glossary: Somnolence\"  class=\"glossaryLink\">somnolence<\/a> instantan&eacute;e peut &ecirc;tre r&eacute;alis&eacute;e avant chaque latence (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/28\/1305\/\"><strong>&Eacute;chelle de somnolence instantan&eacute;e<\/strong><\/a>).<\/li>\n<\/ul>\n<h2><span style=\"font-size: 14pt;\">Indications<\/span><\/h2>\n<p>Recommand&eacute; pour &eacute;valuer :<\/p>\n<ul>\n<li>La capacit&eacute; d&rsquo;une personne &agrave; rester &eacute;veill&eacute;e lorsque son hypersomnolence constitue un probl&egrave;me personnel (<a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/handicap\/\" title=\"Glossary: Handicap\"  class=\"glossaryLink\">handicap<\/a>) ou de s&eacute;curit&eacute; publique :\n<ul>\n<li>Conduite automobile en particulier dans le cadre m&eacute;dico-l&eacute;gal de l&rsquo;arr&ecirc;t&eacute; du 18 d&eacute;cembre 2015 (examen demand&eacute; par le m&eacute;decin agr&eacute;&eacute; de la commission d&eacute;partementale d&rsquo;aptitude m&eacute;dicale au permis de conduire) (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/12\/01\/conduite-automobile-et-medecine-du-sommeil\/\"><strong>Conduite automobile<\/strong><\/a>).<\/li>\n<li>Risque professionnel (examen possiblement demand&eacute; par le m&eacute;decin du travail).<\/li>\n<\/ul>\n<\/li>\n<li>La r&eacute;ponse sur la plainte d&rsquo;hypersomnolence d&rsquo;un traitement somnologique (PPC, OAM, traitements &eacute;veillant, allongement du temps de sommeil, etc.) (cf. Fiches : <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/28\/pression-positive-continue-ppc\/\">PPC<\/a>, <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/29\/orthese-davancee-mandibulaire-oam\/\">OAM<\/a> &amp; <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/29\/les-traitements-eveillant\/\">Traitements &eacute;veillant<\/a><\/strong>)<\/li>\n<\/ul>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"514\" height=\"710\" src=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/sfrms-c19.png\" alt=\"\" class=\"wp-image-3231\" srcset=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/sfrms-c19.png 514w, https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/sfrms-c19-217x300.png 217w\" sizes=\"auto, (max-width: 514px) 100vw, 514px\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Analyse<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li>Visuelle par un m&eacute;decin ayant une comp&eacute;tence en m&eacute;decine du sommeil.<\/li><li>D&eacute;finitions des indices physiologiques du sommeil recueillis :<ul><li><strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/endormissement\/\" title=\"Glossary: Endormissement\" class=\"glossaryLink\">Endormissement<\/a> <\/strong>: une &eacute;poque de n&rsquo;importe quel stade de sommeil.<\/li><li><strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/latence-dendormissement\/\" title=\"Glossary: Latence d'endormissement\" class=\"glossaryLink\">Latence d&rsquo;endormissement<\/a><\/strong> : d&eacute;lai avant l&rsquo;&eacute;poque d&rsquo;endormissement pour<br>chaque latence (si pas d&rsquo;endormissement la latence est de 40 min).<\/li><li><strong>Latence d&rsquo;endormissement moyenne<\/strong> : moyenne des latences d&rsquo;endormissement des 4 tests.<\/li><\/ul><\/li><\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Interpr&eacute;tation<\/h2>\n\n\n\n<ul class=\"wp-block-list\"><li><strong>LE moyenne <\/strong>:<ul><li>&gt; 33 min: pas de risque concernant la conduite automobile,<\/li><li>&lt; 33 min: risque interm&eacute;diaire concernant la conduite automobile,<\/li><li>&lt; 19 min: risque &eacute;lev&eacute; concernant la conduite automobile, surtout si le sujet<br>rapporte une somnolence au volant (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/28\/echelle-de-severite-de-la-somnolence-au-volant\/\"><strong>&Eacute;chelle de s&eacute;v&eacute;rit&eacute; de la somnolence au volant<\/strong><\/a>).<\/li><\/ul><\/li><li><strong>Attention<\/strong> : l&rsquo;aptitude m&eacute;dicale au permis de conduire ou au poste professionnel ne sont pas donn&eacute;es par le m&eacute;decin du sommeil qui fournit uniquement un avis sur le niveau de somnolence au TME au m&eacute;decin agr&eacute;&eacute; ou au m&eacute;decin du travail. Par contre, le m&eacute;decin du sommeil a une obligation d&rsquo;information du patient sur le<br>risque accidentel et qu&rsquo;il doit d&eacute;clarer son trouble hypersomnolence au m&eacute;decin agr&eacute;&eacute; et au m&eacute;decin du travail (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/12\/01\/conduite-automobile-et-medecine-du-sommeil\/\"><strong>Conduite automobile<\/strong><\/a>).<\/li><\/ul>\n","protected":false},"excerpt":{"rendered":"<p>D&eacute;finition Le test de maintien d&rsquo;&eacute;veil (TME) est un examen paraclinique sp&eacute;cifique &agrave; l&rsquo;exploration du sommeil. Le TME est une mesure de la latence d&rsquo;endormissement (LE) en conditions contr&ocirc;l&eacute;es. La LE est mesur&eacute;e sur un hypnogramme r&eacute;alis&eacute; sur chaque test. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7],"tags":[],"class_list":["post-1031","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-enregistrement-du-sommeil"],"featured_image_src":"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/UTwTq5an_normal.png","blog_images":{"medium":"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/UTwTq5an_normal.png","large":"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/UTwTq5an_normal.png"},"_links":{"self":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1031","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1031"}],"version-history":[{"count":8,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1031\/revisions"}],"predecessor-version":[{"id":4064,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1031\/revisions\/4064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/media\/4061"}],"wp:attachment":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1031"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1031"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1031"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}