{"id":1087,"date":"2021-11-24T14:59:53","date_gmt":"2021-11-24T13:59:53","guid":{"rendered":"https:\/\/sfrms-app.fr\/?p=1087"},"modified":"2022-11-06T00:38:56","modified_gmt":"2022-11-05T23:38:56","slug":"hypothese-diagnostique-devant-une-insomnie","status":"publish","type":"post","link":"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/24\/hypothese-diagnostique-devant-une-insomnie\/","title":{"rendered":"Hypoth\u00e8se diagnostique devant une insomnie"},"content":{"rendered":"<h2><span style=\"font-size: 14pt;\">D&eacute;finition autour de l&rsquo;insomnie<\/span><\/h2>\n<p><strong>La plainte d&rsquo;insomnie<\/strong><\/p>\n<ul>\n<li>L&rsquo;insomnie est une plainte subjective en lien avec l&rsquo;impression d&rsquo;un <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/sommeil\/\" title=\"Glossary: Sommeil\"  class=\"glossaryLink\">sommeil<\/a> de quantit&eacute; et\/ou de qualit&eacute; inad&eacute;quate.<\/li>\n<\/ul>\n<p><strong>Le <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/syndrome\/\" title=\"Glossary: Syndrome\"  class=\"glossaryLink\">syndrome<\/a> d&rsquo;insomnie<\/strong><\/p>\n<ul>\n<li><strong>Le syndrome d&rsquo;insomnie<\/strong> est un ensemble de plaintes d&rsquo;insomnie qui entra&icirc;ne une <strong>alt&eacute;ration du fonctionnement de l&rsquo;individu &agrave; l&rsquo;&eacute;veil<\/strong>, sans pr&eacute;juger de sa cause.<\/li>\n<\/ul>\n<p><strong>Le trouble insomnie<\/strong><\/p>\n<ul>\n<li>Le trouble insomnie est un syndrome d&rsquo;insomnie li&eacute; &agrave; une <strong>hyperactivation du fonctionnement des syst&egrave;mes d&rsquo;&eacute;veil<\/strong> consid&eacute;r&eacute;e comme une condition m&eacute;dicale (pathologie).<\/li>\n<li>Dans le trouble insomnie, le syndrome d&rsquo;insomnie n&rsquo;est, le plus souvent, que partiellement r&eacute;versible apr&egrave;s obtention d&rsquo;une am&eacute;lioration de la cause initiale (Cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/12\/27\/trouble-insomnie-chronique\/\"><strong>Trouble insomnie chronique<\/strong><\/a>).<\/li>\n<\/ul>\n<p><strong>L&rsquo;insomnie fatale familiale<\/strong><\/p>\n<ul>\n<li>L&rsquo;insomnie fatale familiale (IFF) est <strong>une maladie rare h&eacute;r&eacute;ditaire de transmission autosomique dominante<\/strong>, faisant partie du groupe des enc&eacute;phalopathies spongiformes transmissibles humaines (comme la maladie de Creutzfeldt-Jacob).<\/li>\n<li>L&rsquo;IFF est li&eacute;e &agrave; une mutation du g&egrave;ne de la prot&eacute;ine prion (g&egrave;ne PRNP). Cette mutation entra&icirc;ne une gliose astrocytaire principalement dans le thalamus, d&eacute;connectant ainsi le cortex de l&rsquo;hypothalamus et de la formation r&eacute;ticul&eacute;e ascendante activatrice (FRAA), perturbant ainsi le fonctionnement des boucles thalamo-corticales (Cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/12\/14\/physiologie-de-leveil-et-de-lendormissement\/\"><strong>Physiologie de l&rsquo;&eacute;veil et de l&rsquo;endormissement<\/strong><\/a>).<\/li>\n<li>L&rsquo;IFF associe un syndrome d&rsquo;insomnie chronique s&eacute;v&egrave;re, avec <strong>agrypnie<\/strong> (perte totale prolong&eacute;e du sommeil), une dysautonomie, des troubles moteurs, puis l&rsquo;apparition d&rsquo;une d&eacute;mence.<\/li>\n<\/ul>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"502\" height=\"715\" src=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture.png\" alt=\"\" class=\"wp-image-1088\" srcset=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture.png 502w, https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-211x300.png 211w\" sizes=\"auto, (max-width: 502px) 100vw, 502px\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Les trois dimensions du syndrome d&rsquo;insomnie<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Le syndrome d&rsquo;insomnie comporte trois composantes symptomatiques (Cf. Fiche : <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/27\/echelle-de-severite-de-linsomnie\/\">&Eacute;chelle de s&eacute;v&eacute;rit&eacute; de l&rsquo;insomnie<\/a><\/strong>) :<br>&mdash; <strong>La difficult&eacute; d&rsquo;<a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/endormissement\/\" title=\"Glossary: Endormissement\" class=\"glossaryLink\">endormissement<\/a><\/strong>,<br>&mdash; <strong>La difficult&eacute; de maintien de sommeil<\/strong> (r&eacute;veil pendant le sommeil),<br>&mdash; <strong>Le r&eacute;veil pr&eacute;coce<\/strong>.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Les causes d&rsquo;insomnie<\/h2>\n\n\n\n<p><strong>Facteurs externes<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une cause externe est une cause li&eacute;e &agrave; un facteur venant de l&rsquo;ext&eacute;rieur <strong>perturbant les syst&egrave;mes de sommeil et de l&rsquo;&eacute;veil<\/strong>.<\/li>\n\n\n\n<li>Il peut s&rsquo;agir :\n<ul class=\"wp-block-list\">\n<li>d&rsquo;une condition environnementale involontaire ne permettant pas d&rsquo;assurer un sommeil satisfaisant (par ex : bruit, exposition aux &eacute;crans) qui a un effet stimulant des syst&egrave;mes d&rsquo;&eacute;veil,<\/li>\n\n\n\n<li>de la prise d&rsquo;une substance <strong>&eacute;veillante<\/strong> ou du <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/sevrage\/\" title=\"Glossary: Sevrage\"  class=\"glossaryLink\">sevrage<\/a> d&rsquo;une substance s&eacute;dative<\/strong> (modifiant la balance entre syst&egrave;mes d&rsquo;&eacute;veil et de sommeil, Cf. Fiche : <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/12\/14\/physiologie-de-leveil-et-de-lendormissement\/\">Physiologie de l&rsquo;&eacute;veil et de l&rsquo;endormissement<\/a><\/strong>).<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n\n\n\n<p><strong>Facteurs li&eacute;s au comportement li&eacute; au sommeil<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Une cause comportementale est :\n<ul class=\"wp-block-list\">\n<li>Un temps pass&eacute; au lit sup&eacute;rieur aux besoins physiologiques en termes de dur&eacute;e de sommeil au regard du <strong>somnotype long\/court dormeur<\/strong> du sujet (Cf. Fiche : <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/23\/le-sommeil-en-fonction-de-lage\/\">Le sommeil en fonction de l&rsquo;&acirc;ge<\/a><\/strong>),<\/li>\n\n\n\n<li>Un horaire de sommeil inappropri&eacute; au regard du <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/chronotype\/\" title=\"Glossary: Chronotype\"  class=\"glossaryLink\">chronotype<\/a> vesp&eacute;rale\/matinal<\/strong> du sujet.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>pouvant perturber le conditionnement au sommeil.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Autres pathologies<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>De nombreuses pathologies m&eacute;dicales peuvent entra&icirc;ner de l&rsquo;insomnie.<\/li>\n\n\n\n<li>Les pathologies les plus fr&eacute;quentes sont :\n<ul class=\"wp-block-list\">\n<li>Les troubles douloureux chroniques,<\/li>\n\n\n\n<li>Les troubles psychiatriques.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>Toutes les pathologies chroniques peuvent &ecirc;tre associ&eacute;es &agrave; de l&rsquo;insomnie, notamment en lien avec le <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/stress\/\" title=\"Glossary: Stress\"  class=\"glossaryLink\">stress<\/a>.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"632\" height=\"781\" src=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-1.png\" alt=\"\" class=\"wp-image-1089\" srcset=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-1.png 632w, https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-1-243x300.png 243w\" sizes=\"auto, (max-width: 632px) 100vw, 632px\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Troubles du sommeil<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>La plupart des troubles du sommeil peuvent provoquer de l&rsquo;insomnie du fait de la perturbation du sommeil par l&rsquo;&eacute;v&egrave;nement arrivant au cours du sommeil et pouvant le perturber.<\/li>\n\n\n\n<li>Le type de plainte dans le syndrome d&rsquo;insomnie peut orienter vers le type de trouble du sommeil&nbsp;:\n<ul class=\"wp-block-list\">\n<li><strong>La difficult&eacute; d&rsquo;endormissement :<\/strong> <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/syndrome\/\" title=\"Glossary: Syndrome\"  class=\"glossaryLink\">Syndrome<\/a> des jambes sans repos, syndrome de <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/retard-de-phase\/\" title=\"Glossary: Retard de phase\" class=\"glossaryLink\">retard de phase<\/a>,<\/li>\n\n\n\n<li><strong>La difficult&eacute; de maintien de sommeil :<\/strong> Syndrome d&rsquo;apn&eacute;es et hypopn&eacute;es obstructives ou centrales du sommeil, Syndrome d&rsquo;<a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/hypoventilation\/\" title=\"Glossary: Hypoventilation\" class=\"glossaryLink\">hypoventilation<\/a> pendant le sommeil, Syndrome des mouvements p&eacute;riodiques des jambes pendant le sommeil, Parasomnies, Bruxisme li&eacute; au sommeil, Narcolepsie.<\/li>\n\n\n\n<li><strong>Le r&eacute;veil pr&eacute;coce <\/strong>: Syndrome d&rsquo;<a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/avance-de-phase\/\" title=\"Glossary: Avance de phase\" class=\"glossaryLink\">avance de phase<\/a>.<\/li>\n<\/ul>\n<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>D&eacute;finition autour de l&rsquo;insomnie La plainte d&rsquo;insomnie L&rsquo;insomnie est une plainte subjective en lien avec l&rsquo;impression d&rsquo;un sommeil de quantit&eacute; et\/ou de qualit&eacute; inad&eacute;quate. Le syndrome d&rsquo;insomnie Le syndrome d&rsquo;insomnie est un ensemble de plaintes d&rsquo;insomnie qui entra&icirc;ne une alt&eacute;ration [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[10],"tags":[],"class_list":["post-1087","post","type-post","status-publish","format-standard","hentry","category-arbres-decisionnels"],"featured_image_src":null,"blog_images":{"medium":null,"large":null},"_links":{"self":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1087","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1087"}],"version-history":[{"count":11,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1087\/revisions"}],"predecessor-version":[{"id":4740,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1087\/revisions\/4740"}],"wp:attachment":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1087"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1087"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1087"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}