{"id":1369,"date":"2021-11-28T16:17:39","date_gmt":"2021-11-28T15:17:39","guid":{"rendered":"https:\/\/sfrms-app.fr\/?p=1369"},"modified":"2022-11-05T23:53:34","modified_gmt":"2022-11-05T22:53:34","slug":"pression-positive-continue-ppc","status":"publish","type":"post","link":"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/28\/pression-positive-continue-ppc\/","title":{"rendered":"Pression positive continue (PPC)"},"content":{"rendered":"<h2><span style=\"font-size: 14pt;\">Mode d&rsquo;action<\/span><\/h2>\n<p>La PPC est un mode de support respiratoire permettant de maintenir ouvertes &agrave; tous les stades du cycle respiratoire les voies a&eacute;riennes sup&eacute;rieures.<\/p>\n<h2><span style=\"font-size: 14pt;\">Indications<\/span><\/h2>\n<p>La PPC est rembours&eacute;e dans les conditions suivantes :<\/p>\n<ul>\n<li>SAHOS associ&eacute; &agrave; 3 sympt&ocirc;mes (ronflements, <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/somnolence\/\" title=\"Glossary: Somnolence\"  class=\"glossaryLink\">somnolence<\/a> diurne, suffocation pendant le <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/sommeil\/\" title=\"Glossary: Sommeil\"  class=\"glossaryLink\">sommeil<\/a>, <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/nycturie\/\" title=\"Glossary: Nycturie\"  class=\"glossaryLink\">nycturie<\/a>, c&eacute;phal&eacute;es matinales, <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/fatigue\/\" title=\"Glossary: Fatigue\"  class=\"glossaryLink\">fatigue<\/a>).<\/li>\n<li>ET\n<ul>\n<li>IAH &gt; 30\/h,<\/li>\n<li>IAH entre 15 et 30\/h sur PSG avec <strong>risque accidentel<\/strong> (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/12\/01\/conduite-automobile-et-medecine-du-sommeil\/\"><strong>Conduite automobile<\/strong><\/a>) et\/ou <strong>somnolence diurne s&eacute;v&egrave;re<\/strong> (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/27\/echelle-de-severite-de-la-somnolence\/\"><strong>&Eacute;chelle de s&eacute;v&eacute;rit&eacute; de la somnolence<\/strong><\/a>),<\/li>\n<li>IAH entre 15 et 30\/H sur PSG ou PV avec <strong style=\"font-family: Roboto; font-size: revert; color: initial;\">comorbidit&eacute;s respiratoires ou cardiovasculaires s&eacute;v&egrave;res<\/strong><span style=\"font-family: Roboto; font-size: revert; color: initial;\">.<\/span><\/li>\n<\/ul>\n<\/li>\n<\/ul>\n<p>Y penser &eacute;galement en cas de plainte d&rsquo;insomnie, de maintien, de <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/comorbidite\/\" title=\"Glossary: Comorbidit&eacute;\" class=\"glossaryLink\">comorbidit&eacute;<\/a> m&eacute;tabolique ou psychiatrique s&eacute;v&egrave;re<\/strong> ou autres, suivant le <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/contexte\/\" title=\"Glossary: Contexte\"  class=\"glossaryLink\">contexte<\/a> clinique, avec alors avis m&eacute;dical motiv&eacute; aupr&egrave;s du m&eacute;decin conseil.<\/p>\n<h2><span style=\"font-size: 14pt;\">Contre-indications<\/span><\/h2>\n<p>Les contre-indications sont exceptionnelles, il s&rsquo;agit principalement du risque de barotraumatisme avec cons&eacute;quence grave comme la br&egrave;che ost&eacute;o-m&eacute;ning&eacute;e.<\/p>\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"484\" height=\"520\" src=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-29.png\" alt=\"\" class=\"wp-image-1371\" srcset=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-29.png 484w, https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-29-279x300.png 279w\" sizes=\"auto, (max-width: 484px) 100vw, 484px\"\/><\/figure>\n<\/div>\n\n\n<p><strong>Persistance d&rsquo;&eacute;v&egrave;nements respiratoires<\/strong><br>La PPC a un algorithme int&eacute;gr&eacute; de d&eacute;tection des &eacute;v&egrave;nements respiratoires sur le signal du d&eacute;bit (Apn&eacute;es, hypopn&eacute;es, limitations de d&eacute;bit, ronflement)<br>Augmentation rapide de la pression en cas de d&eacute;tection d&rsquo;&eacute;v&egrave;nements<br>Baisse progressive de la pression en l&rsquo;absence de d&eacute;tection d&rsquo;&eacute;v&egrave;nements<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">R&egrave;gles de prescription<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li>L&rsquo;initiation et les premiers renouvellements de la PPC doivent se faire par un <strong>m&eacute;decin ayant une formation reconnue en m&eacute;decine sommeil.<\/strong><\/li>\n\n\n\n<li>Le prescripteur doit r&eacute;aliser la prescription sur une <strong>demande d&rsquo;accord pr&eacute;alable (DAP)<\/strong> pour &laquo; le traitement du <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/syndrome\/\" title=\"Glossary: Syndrome\"  class=\"glossaryLink\">syndrome<\/a> d&rsquo;apn&eacute;es hypopn&eacute;es du sommeil chez les patients de plus de 16 ans &raquo; et pr&eacute;ciser :\n<ul class=\"wp-block-list\">\n<li>le type de prescription (initiale\/renouvellement\/modification des r&eacute;glages),<\/li>\n\n\n\n<li>le mode de pression et ses r&eacute;glages (autopilot&eacute;e\/pression fixe\/pression min et max \/ rampe\/confort expiratoire) selon une titration automatique ou manuelle,<\/li>\n\n\n\n<li>le type d&rsquo;interface (masque nasal, narinaire, facial),<\/li>\n\n\n\n<li>les accessoires (humidificateur chauffant, circuit chauffant, mentonni&egrave;re, harnais),<\/li>\n\n\n\n<li>refus ou intol&eacute;rance d&rsquo;OAM.<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li>La DAP initiale est renouvel&eacute;e &agrave; 4 mois puis annuellement.<\/li>\n\n\n\n<li>Par d&eacute;rogation, &agrave; partir de la 4e prescription, le m&eacute;decin traitant peut r&eacute;aliser le renouvellement si le patient accepte de lui communiquer ses donn&eacute;es d&rsquo;observance, s&rsquo;il est observant, sous r&eacute;serve de l&rsquo;absence d&rsquo;effets ind&eacute;sirables li&eacute;s &agrave; la PPC ou d&rsquo;&eacute;v&eacute;nement intercurrent susceptible de modifier la prise en charge.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Mise en place<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Deux modes de PPC : autopilot&eacute; et fixe.<\/strong><\/li>\n\n\n\n<li><strong>Ces deux modes sont &eacute;quivalents sur l&rsquo;observance et l&rsquo;efficacit&eacute;<\/strong>, la pression fixe est recommand&eacute;e dans les situations suivantes : insuffisance cardiaque (recommandation forte), insuffisance respiratoire s&eacute;v&egrave;re, overlapp syndrome, SOH, HTA s&eacute;v&egrave;re ou r&eacute;sistante.<\/li>\n\n\n\n<li><strong>R&eacute;glage en mode autopilot&eacute;<\/strong> : ajustement automatique du niveau de pression entre une pression min et max &agrave; d&eacute;finir.<\/li>\n\n\n\n<li><strong>R&eacute;glage en mode pression fixe<\/strong> : pression fixe, n&eacute;cessitant une titration pr&eacute;alable dans un centre du sommeil ou au domicile en fonction des donn&eacute;es ant&eacute;rieures de pression autopilot&eacute;e (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/28\/analyse-et-interpretation-dun-rapport-de-pression-positive-continue-ppc\/\"><strong>Analyse et interpr&eacute;tation d&rsquo;un rapport de PPC<\/strong><\/a>).<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"471\" height=\"632\" src=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-30.png\" alt=\"\" class=\"wp-image-1372\" srcset=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-30.png 471w, https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-30-224x300.png 224w\" sizes=\"auto, (max-width: 471px) 100vw, 471px\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Surveillance des effets ind&eacute;sirables<\/h2>\n\n\n\n<p><strong>Surveillance de la <a href=\"https:\/\/sfrms-app.fr\/index.php\/glossary\/tolerance\/\" title=\"Glossary: Tol&eacute;rance\"  class=\"glossaryLink\">tol&eacute;rance<\/a><\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>ORL : fuites, hyper-sialorrh&eacute;e, s&eacute;cheresse nasale et\/ou buccale, obstruction nasale, rhinorrh&eacute;e, &eacute;pistaxis, sensation d&rsquo;&eacute;touffement (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/27\/echelle-de-lobstruction-nasale\/\"><strong>&Eacute;chelle de l&rsquo;obstruction nasale<\/strong><\/a>, envisager chirurgie possible, cf. Fiches : <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/29\/chirurgie-orl-et-maxillo-faciale\/\">Chirurgie ORL et Maxillo-Faciale<\/a> &amp; <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/29\/les-traitements-par-voie-nasale\/\">Traitements par voie nasale<\/a><\/strong>),<\/li>\n\n\n\n<li>Dermatologique : signes d&rsquo;irritation, d&rsquo;&eacute;ryth&egrave;me ou de l&eacute;sions cutan&eacute;es,<\/li>\n\n\n\n<li>Digestive : a&eacute;rophagie, m&eacute;t&eacute;orisme,<\/li>\n\n\n\n<li>Somnologique : plainte d&rsquo;insomnie, bruit.<\/li>\n<\/ul>\n\n\n\n<p><strong>Surveillance de l&rsquo;adh&eacute;sion<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Mauvaise compr&eacute;hension du fonctionnement et de l&rsquo;int&eacute;r&ecirc;t de la PPC par le patient ou le partenaire de lit (cf. Fiches : <strong><a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/27\/echelle-de-decision-du-port-de-ppc\/\">&Eacute;chelle de d&eacute;cision du port de PPC<\/a> &amp; <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/27\/echelle-defficacite-personnelle-concernant-le-port-de-la-ppc\/\" data-type=\"URL\" data-id=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/27\/echelle-defficacite-personnelle-concernant-le-port-de-la-ppc\/\">&Eacute;chelle d&rsquo;efficacit&eacute; personnelle concernant le port de la PPC<\/a><\/strong>),<\/li>\n\n\n\n<li>Faible perception de l&rsquo;efficacit&eacute; ressentie de la PPC.<\/li>\n<\/ul>\n\n\n\n<h2 class=\"wp-block-heading\">Suivi d&rsquo;efficacit&eacute;<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Efficacit&eacute; clinique<\/strong>\n<ul class=\"wp-block-list\">\n<li>R&eacute;duction de la plainte de somnolence et d&rsquo;insomnie,<\/li>\n\n\n\n<li>R&eacute;duction des sympt&ocirc;mes sp&eacute;cifiques du SAHOS (en particulier nycturie et c&eacute;phal&eacute;es matinales),<\/li>\n\n\n\n<li>Stabilisation ou am&eacute;lioration des comorbidit&eacute;s,<\/li>\n\n\n\n<li>Diminution du risque accidentel (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/12\/01\/conduite-automobile-et-medecine-du-sommeil\/\"><strong>Conduite automobile<\/strong><\/a>).<\/li>\n<\/ul>\n<\/li>\n\n\n\n<li><strong>Efficacit&eacute; paraclinique<\/strong>: l&rsquo;efficacit&eacute; sur la somnolence peut &ecirc;tre contr&ocirc;l&eacute;e si n&eacute;cessaire par la r&eacute;alisation d&rsquo;un TME (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/23\/procedure-de-realisation-des-tests-de-maintien-deveil-et-valeurs-normatives\/\"><strong>TME<\/strong><\/a>).<\/li>\n\n\n\n<li>Analyse et interpr&eacute;tation du rapport de PPC (cf. Fiche : <a href=\"https:\/\/sfrms-app.fr\/index.php\/2021\/11\/28\/analyse-et-interpretation-dun-rapport-de-pression-positive-continue-ppc\/\"><strong>Analyse et interpr&eacute;tation du rapport de PPC<\/strong><\/a>).<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"474\" height=\"562\" src=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-31.png\" alt=\"\" class=\"wp-image-1374\" srcset=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-31.png 474w, https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-31-253x300.png 253w\" sizes=\"auto, (max-width: 474px) 100vw, 474px\"\/><\/figure>\n<\/div>\n\n\n<h2 class=\"wp-block-heading\">Conditions de remboursement de la PPC (JO 16\/12\/2017) et JORF n&deg;0042 18\/02\/21<\/h2>\n\n\n\n<ul class=\"wp-block-list\">\n<li><strong>Forfait 9.<\/strong><\/li>\n\n\n\n<li>Forfait hebdomadaire (prise en charge : 60 % par l&rsquo;Assurance Maladie et 40 % par la mutuelle du patient).<\/li>\n\n\n\n<li>Montant du forfait que per&ccedil;oit le prestataire du sommeil d&eacute;pend de l&rsquo;observance du patient et du mode de suivi.<\/li>\n<\/ul>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"385\" height=\"205\" src=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-32.png\" alt=\"\" class=\"wp-image-1375\" srcset=\"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-32.png 385w, https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/Capture-32-300x160.png 300w\" sizes=\"auto, (max-width: 385px) 100vw, 385px\"\/><\/figure>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>Mode d&rsquo;action La PPC est un mode de support respiratoire permettant de maintenir ouvertes &agrave; tous les stades du cycle respiratoire les voies a&eacute;riennes sup&eacute;rieures. Indications La PPC est rembours&eacute;e dans les conditions suivantes : SAHOS associ&eacute; &agrave; 3 sympt&ocirc;mes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":4061,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[12,29],"tags":[],"class_list":["post-1369","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-traitement","category-traitements-des-troubles-respiratoires-du-sommeil"],"featured_image_src":"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/UTwTq5an_normal.png","blog_images":{"medium":"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/UTwTq5an_normal.png","large":"https:\/\/sfrms-app.fr\/wp-content\/uploads\/2021\/11\/UTwTq5an_normal.png"},"_links":{"self":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1369","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/comments?post=1369"}],"version-history":[{"count":9,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1369\/revisions"}],"predecessor-version":[{"id":4705,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/posts\/1369\/revisions\/4705"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/media\/4061"}],"wp:attachment":[{"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/media?parent=1369"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/categories?post=1369"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/sfrms-app.fr\/index.php\/wp-json\/wp\/v2\/tags?post=1369"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}